



{"id":670,"date":"2020-02-21T13:40:40","date_gmt":"2020-02-21T16:40:40","guid":{"rendered":"https:\/\/www.sidomus.com\/noticias\/?p=670"},"modified":"2020-02-21T15:31:09","modified_gmt":"2020-02-21T18:31:09","slug":"fachadas-por-que-es-importante-cuidarlas","status":"publish","type":"post","link":"https:\/\/www.sidomus.com\/noticias\/2020\/02\/21\/fachadas-por-que-es-importante-cuidarlas\/","title":{"rendered":"Fachadas: por qu\u00e9 es importante cuidarlas"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\"><em>El cuidado de las fachadas de edificios, comercios y viviendas en general va mucho m\u00e1s all\u00e1 que una cuesti\u00f3n est\u00e9tica. En esta nota, te contamos c\u00f3mo mantener fachadas, qui\u00e9n debe hacerlo y cu\u00e1ndo es necesario pedir asesoramiento.<\/em><\/h4>\n\n\n\n<p>Cualquier da\u00f1o en una fachada, por m\u00ednimo o inofensivo que parezca, puede repercutir en el interior de un inmueble. <strong>Las fachadas son algo as\u00ed como la piel de los edificios y viviendas, por eso es tan importante una manutenci\u00f3n adecuada, cuidado y\/o asesoramiento en la eventualidad de reformas, mejoras, o incluso obras.<\/strong>  Adem\u00e1s de ser &#8220;la piel&#8221; de una vivienda, una fachada tambi\u00e9n es su la carta de presentaci\u00f3n, es decir, la c\u00e1scara por la cual nos fascinamos o salimos espantados de un departamento o vivienda. En este sentido, la sugerencia principal a tener en cuenta es muy similar a la que inquilinos y propietarios deben considerar si sufren alg\u00fan desperfecto en sus propiedades: en vez de esperar hay que llamar al consorcio, informar, reclamar, insistir. Con respecto al cuidado de las fachadas, el accionar es el mismo:<strong> hay que estar atentos a peque\u00f1os desperfectos que puedan surgir para poder solucionarlos antes de que causen un da\u00f1o mayor<\/strong>. Un ejemplo de algunos de estos desperfectos son las humedades o grietas, tan comunes con el paso del tiempo.<\/p>\n\n\n\n<p>Las fachadas son manutenciones comunes o que se costean &#8220;en com\u00fan&#8221;, por eso, es probable que <strong>el costo de mantenerlas o revisarlas aparezca como un gasto extraordinario en la liquidaci\u00f3n de expensas<\/strong>. Esto \u00faltimo significa que la manutenci\u00f3n es responsabilidad de los propietarios y no de los inquilinos.<\/p>\n\n\n\n<p><strong>A continuaci\u00f3n, algunos puntos a tener en cuenta cuando evaluamos el estado de las fachadas:<\/strong><\/p>\n\n\n\n<ol><li>Para garantizar un correcto mantenimiento <strong>hay que monitorear y\/o revisar el estado de las fachadas en forma peri\u00f3dica<\/strong>. Los edificios con una antig\u00fcedad superior a 50 a\u00f1os deben presentar informes especiales que garanticen su estado o eventual deterioro. Una fachada mal mantenida asegura problemas en el interior del edificio, y adem\u00e1s <strong>puede poner en serio riesgo a la comunidad.<\/strong> Una fachada en mal estado puede significar, por ejemplo y en \u00faltima instancia, el pre\u00e1mbulo de un derrumbe. <\/li><li><strong>La\u00a0rehabilitaci\u00f3n de fachadas<\/strong>\u00a0es una necesidad peri\u00f3dica para la gran mayor\u00eda de los edificios, ya que con el paso del tiempo los edificios se van deteriorando debido principalmente a los efectos del clima y la contaminaci\u00f3n. Hay empresas especializadas en esos temas.<\/li><li><strong>Los consorcios deber\u00edan siempre tener un presupuesto<\/strong> o saldo a favor de la posible o eventual rehabilitaci\u00f3n de fachadas. <\/li><li><strong>Deterioros en la fachada influyen en la calidad de vida de las personas que habitan en el edificio<\/strong>, como el aislamiento de fr\u00edo, el aislamiento ac\u00fastico, entre otros.<\/li><li><strong>Una fachada restaurada o bien cuidada revaloriza el valor de las viviendas que la conforman.<\/strong> Una alternativa que agrega valor es invertir en fachadas con correcto aislamiento para evitar perdidas de energ\u00eda: la calefacci\u00f3n, por ejemplo, es un gasto que puede controlarse con una fachada correctamente aislada. Adem\u00e1s de calidad de vida, se gana un ahorro importante de energ\u00eda.<\/li><\/ol>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Con <a href=\"http:\/\/www.sidomus.com\">Sidomus<\/a>, adem\u00e1s de estar informado, pod\u00e9s conocer mejor el estado general de tu edificio, tus expensas y tu administrador. Si administr\u00e1s edificios, recordarte que con <a href=\"http:\/\/www.sidomus.com\">SiDomus <\/a>es posible gestionar mejor tus tareas de un \u00fanico panel de control visualizando la totalidad de consorcios que manejes. Y mucho m\u00e1s. Para conocer m\u00e1s ventajas, pod\u00e9s leer m\u00e1s <a href=\"http:\/\/www.sidomus.com\">ac\u00e1<\/a>. Si adem\u00e1s quer\u00e9s navegar nuestro blog de noticias, pod\u00e9s hacerlo <a href=\"http:\/\/www.sidomus.com\/noticias\">ac\u00e1<\/a>. Por otras consultas con respecto al sistema y su activaci\u00f3n <em>gratuita <\/em>de prueba, pod\u00e9s llamarnos al  0810&nbsp;268 0115 o escribirnos a hola@sidomus.com<\/h4>\n\n\n\n<p>Gracias por estar, pasar y leer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cuidado de las fachadas de edificios, comercios y viviendas en general va mucho m\u00e1s all\u00e1 que una cuesti\u00f3n est\u00e9tica. En esta nota, te contamos c\u00f3mo mantener fachadas, qui\u00e9n debe hacerlo y cu\u00e1ndo es necesario pedir asesoramiento.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[67,62,292,293,296,303,294,301,297,302,295,298,300,299,39],"_links":{"self":[{"href":"https:\/\/www.sidomus.com\/noticias\/wp-json\/wp\/v2\/posts\/670"}],"collection":[{"href":"https:\/\/www.sidomus.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sidomus.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sidomus.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sidomus.com\/noticias\/wp-json\/wp\/v2\/comments?post=670"}],"version-history":[{"count":7,"href":"https:\/\/www.sidomus.com\/noticias\/wp-json\/wp\/v2\/posts\/670\/revisions"}],"predecessor-version":[{"id":677,"href":"https:\/\/www.sidomus.com\/noticias\/wp-json\/wp\/v2\/posts\/670\/revisions\/677"}],"wp:attachment":[{"href":"https:\/\/www.sidomus.com\/noticias\/wp-json\/wp\/v2\/media?parent=670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sidomus.com\/noticias\/wp-json\/wp\/v2\/categories?post=670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sidomus.com\/noticias\/wp-json\/wp\/v2\/tags?post=670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}